{"id":50,"count":3,"description":"","link":"https:\/\/plaatjemetlogo.nl\/fr\/assortiment\/plaque-dacier-inoxydable\/","name":"Plaque d'acier inoxydable","slug":"plaque-dacier-inoxydable","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Plaque d&#039;acier inoxydable Archieven - PlaatjemetLogo.nl<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/plaatjemetlogo.nl\/fr\/assortiment\/plaque-dacier-inoxydable\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plaque d&#039;acier inoxydable Archieven - PlaatjemetLogo.nl\" \/>\n<meta property=\"og:url\" content=\"https:\/\/plaatjemetlogo.nl\/fr\/assortiment\/plaque-dacier-inoxydable\/\" \/>\n<meta property=\"og:site_name\" content=\"PlaatjemetLogo.nl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/plaatjemetlogo.nl\\\/fr\\\/assortiment\\\/plaque-dacier-inoxydable\\\/\",\"url\":\"https:\\\/\\\/plaatjemetlogo.nl\\\/fr\\\/assortiment\\\/plaque-dacier-inoxydable\\\/\",\"name\":\"Plaque d'acier inoxydable Archieven - PlaatjemetLogo.nl\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/plaatjemetlogo.nl\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/plaatjemetlogo.nl\\\/fr\\\/assortiment\\\/plaque-dacier-inoxydable\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/plaatjemetlogo.nl\\\/fr\\\/assortiment\\\/plaque-dacier-inoxydable\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/plaatjemetlogo.nl\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plaque d'acier inoxydable\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/plaatjemetlogo.nl\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/plaatjemetlogo.nl\\\/fr\\\/\",\"name\":\"PlaatjemetLogo.nl\",\"description\":\"En nog een WordPress site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/plaatjemetlogo.nl\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plaque d'acier inoxydable Archieven - PlaatjemetLogo.nl","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/plaatjemetlogo.nl\/fr\/assortiment\/plaque-dacier-inoxydable\/","og_locale":"fr_FR","og_type":"article","og_title":"Plaque d'acier inoxydable Archieven - PlaatjemetLogo.nl","og_url":"https:\/\/plaatjemetlogo.nl\/fr\/assortiment\/plaque-dacier-inoxydable\/","og_site_name":"PlaatjemetLogo.nl","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/plaatjemetlogo.nl\/fr\/assortiment\/plaque-dacier-inoxydable\/","url":"https:\/\/plaatjemetlogo.nl\/fr\/assortiment\/plaque-dacier-inoxydable\/","name":"Plaque d'acier inoxydable Archieven - PlaatjemetLogo.nl","isPartOf":{"@id":"https:\/\/plaatjemetlogo.nl\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/plaatjemetlogo.nl\/fr\/assortiment\/plaque-dacier-inoxydable\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/plaatjemetlogo.nl\/fr\/assortiment\/plaque-dacier-inoxydable\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/plaatjemetlogo.nl\/fr\/"},{"@type":"ListItem","position":2,"name":"Plaque d'acier inoxydable"}]},{"@type":"WebSite","@id":"https:\/\/plaatjemetlogo.nl\/fr\/#website","url":"https:\/\/plaatjemetlogo.nl\/fr\/","name":"PlaatjemetLogo.nl","description":"En nog een WordPress site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/plaatjemetlogo.nl\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/plaatjemetlogo.nl\/fr\/wp-json\/wp\/v2\/product_cat\/50","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plaatjemetlogo.nl\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/plaatjemetlogo.nl\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/plaatjemetlogo.nl\/fr\/wp-json\/wp\/v2\/product?product_cat=50"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}